{"id":370,"date":"2018-01-05T22:45:50","date_gmt":"2018-01-05T21:45:50","guid":{"rendered":"http:\/\/2018.gaiamedia.org\/deutsch\/?p=370"},"modified":"2018-02-06T22:51:47","modified_gmt":"2018-02-06T21:51:47","slug":"januar-2018-gut-zu-wissen","status":"publish","type":"post","link":"https:\/\/www.gaiamedia.org\/deutsch\/2018\/01\/05\/januar-2018-gut-zu-wissen\/","title":{"rendered":"januar 2018 &#8211; gut zu wissen"},"content":{"rendered":"<p><a href=\"https:\/\/utopia.de\/bestenlisten\"><strong>Bestenliste<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">leben\u00a0<\/span>|\u00a0<span style=\"color: #000000;\">laufend<\/span><br \/>\nHier findet man die besten Produkte f\u00fcr ein nachhaltiges Leben in vielen verschiedenen Sparten.<\/p>\n<p><a href=\"https:\/\/www.heise.de\/tp\/features\/No-poetry-among-water-drinkers-3903144.html\" target=\"_blank\" rel=\"noopener\"><strong>Rausch und Kreativit\u00e4t<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">psychoaktiv\u00a0<\/span>|\u00a0<span style=\"color: #000000;\">\u00a0Telepolis, 3. Dezember 2017<\/span><br \/>\nWie welcher Stoff kreativ macht. Schwer zu glauben: dass Shakespeare Kokain rauchte.<\/p>\n<p><a href=\"https:\/\/www.heise.de\/tp\/features\/Back-to-the-Roots-3893232.html\" target=\"_blank\" rel=\"noopener\"><strong>Holzbauten<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">\u00f6ko\u00a0<\/span>|\u00a0<span style=\"color: #000000;\">Spiegel, Online, 3. Dezember 2017<\/span><br \/>\nDer urbane Holzbau erlebt eine Renaissance. Das archaische, nachhaltige Material wird von meist jungen Architekten eindrucksvoll eingesetzt.<\/p>\n<p><a href=\"http:\/\/www.spiegel.de\/netzwelt\/web\/kopftuch-emoji-veraendert-das-leben-der-16-jaehrigen-rayouf-alhumedhi-a-1180849.html\" target=\"_blank\" rel=\"noopener\"><strong>Pluralit\u00e4t<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">leben\u00a0<\/span>|\u00a0<span style=\"color: #000000;\">Spiegel Online, 3. Dezember 2017<\/span><br \/>\nWeil sie sich nicht vertreten f\u00fchlt, erfindet eine 16j\u00e4hrige Wienerin das Kopftuch-Emoji und setzt sich bei der Computerindustrie durch.<\/p>\n<p><a href=\"https:\/\/www.heise.de\/tr\/artikel\/Cyberdyne-Wieder-gehen-lernen-3907245.html\"><strong>Wieder gehen lernen<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">leben\u00a0<\/span>|\u00a0Technology Review, 4. Dezember 2017<br \/>\nDas Exoskelett HAL l\u00e4sst sich \u00fcber Nervensignale steuern \u2013 und bringt so Gel\u00e4hmte wieder auf die Beine.<\/p>\n<p><a href=\"http:\/\/www.scinexx.de\/wissen-aktuell-22164-2017-12-04.html\"><strong>Himmlisches Metall<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">kultur\u00a0<\/span>|\u00a0scinexx, 4. Dezember 2017<br \/>\nWie Menschen schon Jahrtausende vor Erfindung der Eisenverarbeitung Dolche, Perlen und andere Objekte aus diesem Metall fertigten.<\/p>\n<p><a href=\"http:\/\/www.taz.de\/Die-Wahrheit\/!5463817\/\" target=\"_blank\" rel=\"noopener\"><strong>Treuherzig<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">wissen\u00a0<\/span>|\u00a0TAZ 4. Dezember 2017<br \/>\nK\u00f6nnen Tiere und Pflanzen l\u00fcgen ist hier die Frage \u2013 oder Schluss mit der Verniedlichung!<\/p>\n<p><a href=\"https:\/\/www.nzz.ch\/wissenschaft\/ein-schwarzes-loch-frisst-ueber-seine-verhaeltnisse-ld.1336493\" target=\"_blank\" rel=\"noopener\"><strong>Schwarzes Loch<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">wissen<\/span>|\u00a0NZZ, 6. Dezember 2017<br \/>\nDie Entdeckung eines Quasars in Rekorddistanz stellt Astronomen vor R\u00e4tsel.<\/p>\n<p><a href=\"http:\/\/www.gute-nachrichten.com.de\/2017\/12\/gesundheit\/die-heilpflanze-des-jahres-2017-das-gaensebluemchen\/\" target=\"_blank\" rel=\"noopener\"><strong>Heilender Korbbl\u00fcter<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">\u00f6ko\u00a0<\/span>|\u00a0Gute Nachrichten, 9. Dezember 2017<br \/>\nDie Heilpflanze des Jahres 2017 ist das gute alte G\u00e4nsebl\u00fcmchen, das Linderung verspricht bei vielen Beschwerden.<\/p>\n<p><a href=\"https:\/\/www.heise.de\/tr\/artikel\/Wenn-das-Sexspielzeug-spioniert-3910105.html\" target=\"_blank\" rel=\"noopener\"><strong>Chip rein<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">wissen\u00a0<\/span>|\u00a0Technology Review, 12. Dezember 2017<br \/>\nDas Internet der Dinge dehnt sich in Bereiche aus, in denen es nichts verloren hat.<\/p>\n<p><a href=\"http:\/\/sz-magazin.sueddeutsche.de\/texte\/anzeigen\/46735\" target=\"_blank\" rel=\"noopener\"><strong>Lebenswandel<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">\u00f6ko\u00a0<\/span>|\u00a0S\u00fcddeutsche, 12. Dezember 2017<br \/>\nWas kann der Einzelne gegen globale Missst\u00e4nde wie den Klimawandel unternehmen? Die Soziologen Stephan Lessenich und Harald Welzer geben darauf ganz unterschiedliche Antworten.<\/p>\n<p><a href=\"http:\/\/www.scinexx.de\/wissen-aktuell-22209-2017-12-14.html\" target=\"_blank\" rel=\"noopener\"><strong>Gleich gepolt<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">wissen\u00a0<\/span>|\u00a0scinexx, 14. Dezember 2017<br \/>\nObwohl Arktis und Antarktis an entgegengesetzten Polen der Erde liegen, leben dort \u00e4hnliche Bakterienarten.<\/p>\n<p><a href=\"http:\/\/www.taz.de\/Kulturelle-Oeffnung-in-Saudi-Arabien\/!5470766\/\" target=\"_blank\" rel=\"noopener\"><strong>Licht aus<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">kultur\u00a0<\/span>|\u00a0FAZ, 14. Dezember 2017<br \/>\nNach 35 Jahren sollen in Saudi-Arabien wieder Lizenzen f\u00fcr Lichtspielh\u00e4user vergeben werden.<\/p>\n<p><a href=\"http:\/\/www.sonnenseite.com\/de\/energie\/wie-stromhandel-von-nachbar-zu-nachbar-moeglich-wird.html\" target=\"_blank\" rel=\"noopener\"><strong>Stromhandel<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">\u00f6ko\u00a0<\/span>|\u00a0Sonnenseite,14. Dezember 2017<br \/>\nDas \u201eImpulspapier B\u00fcrgerstromhandel\u201c zeigt konkret, wie Privatpersonen zu Verk\u00e4ufern von erneuerbar erzeugtem Strom an ihre NachbarInnen werden k\u00f6nnen.<\/p>\n<p><a href=\"http:\/\/www.wissenschaft.de\/leben-umwelt\/psychologie\/-\/journal_content\/56\/12054\/21590686\/Gespenstische-H%C3%B6henerlebnisse-analysiert\/\" target=\"_blank\" rel=\"noopener\"><strong>Gespenster am Berg<\/strong><\/a><br \/>\nwissen\u00a0|\u00a0Bild der Wissenschaft, 14. Dezember 2017<br \/>\nSie sehen neben sich einen Phantom-Begleiter, h\u00f6ren Stimmen und lassen sich sogar vom Weg abbringen. Davon berichten Bergsteiger nach Touren in extremen H\u00f6hen auffallend h\u00e4ufig.<\/p>\n<p><a href=\"https:\/\/reset.org\/blog\/eine-neue-plattform-nutzt-die-blockchain-um-extremismus-und-fake-news-zu-bekaempfen-12142017\" target=\"_blank\" rel=\"noopener\"><strong>Gegen Fake News<\/strong><\/a><br \/>\nwissen\u00a0|\u00a0Reset, 14. Dezember 2017<br \/>\nDie neue App der NGO Ananas Foundation geht mit einer offenen Plattform gegen Fake News vor, die Teilnehmer f\u00fcr ihre Beitr\u00e4ge in Cryptow\u00e4hrung entl\u00f6hnt.<\/p>\n<p><a href=\"https:\/\/www.pressetext.com\/#news\/20171215019\" target=\"_blank\" rel=\"noopener\"><strong>Dreidimensional<\/strong><\/a><br \/>\nwissen\u00a0|\u00a0Pressetext, 15. Dezember 2017<br \/>\nEine perforierte Kunststoffscheibe k\u00f6nnte die Medizin revolutionieren und hochaufl\u00f6sende Ultraschallbilder liefern.<\/p>\n<p><a href=\"http:\/\/uncut-news.ch\/2017\/12\/15\/wissenschaft-findet-neue-gene-fuer-ein-laengeres-leben\/\" target=\"_blank\" rel=\"noopener\"><strong>Langlebigkeit<\/strong><\/a><br \/>\nwissen\u00a0|\u00a0Uncut-News, 15. Dezember 2017<br \/>\nWissenschaftler der University of Exeter Medical School stellen fest, dass bisher unentdeckte Gene sich auf die Lebenserwartung von Eltern auswirken.<\/p>\n<p><a href=\"http:\/\/www.huffingtonpost.de\/entry\/so-schaffst-du-es-keine-lebensmittel-mehr-wegzuwerfen_de_5a2fa455e4b046175432f7ef\" target=\"_blank\" rel=\"noopener\"><strong>Wegwerfware?<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">leben\u00a0<\/span>|\u00a0Huffington Post, 18. Dezember 2017<br \/>\nLebensmittelverschwendung beginnt oft schon im Supermarkt. Wir k\u00f6nnen einiges dagegen tun.<\/p>\n<p><a href=\"http:\/\/news.rub.de\/leute\/2017-12-20-ehrenamt-ein-vorbild-sein\" target=\"_blank\" rel=\"noopener\"><strong>Freiwillig<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">leben\u00a0<\/span>|\u00a0Uni Bochum, 20. Dezember 2017<br \/>\nDamit sich mehr Sch\u00fclerinnen mit afrikanischem Migrationshintergrund ein Studium zutrauen, hat Margaret Sia mit anderen eine nachahmenswerte Initiative gegr\u00fcndet.<\/p>\n<p><a href=\"https:\/\/www.woz.ch\/1751\/graphic-novel\/an-europas-raendern\" target=\"_blank\" rel=\"noopener\"><strong>Graphic Novel<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">kultur\u00a0<\/span>|\u00a0WOZ, 21. Dezember 2017<br \/>\nZwei spanische Reporter bereisten die Aussengrenzen der Europ\u00e4ischen Union \u2013 und machten daraus eine ungew\u00f6hnliche Fotoreportage in Form einer Graphic Novel.<\/p>\n<p><a href=\"http:\/\/www.die-gesunde-wahrheit.de\/2017\/12\/23\/wlan\/\" target=\"_blank\" rel=\"noopener\"><strong>Gef\u00e4hrliche Strahlen<\/strong><\/a><br \/>\nleben\u00a0|\u00a0Die gesunde Wahrheit, 23. Dezember 2017<br \/>\nEine Gruppe von schwedischen Sch\u00fclerinnen entwirft ein geniales Experiment um aufzuzeigen, dass Handystrahlen sch\u00e4dlich sind.<\/p>\n<p><a href=\"http:\/\/www.wissenschaft.de\/leben-umwelt\/biologie\/-\/journal_content\/56\/12054\/21770313\/Pflanzen-zeigen-Z%C3%A4hne\/\" target=\"_blank\" rel=\"noopener\"><strong>Pflanzen mit Biss<\/strong><\/a><br \/>\n<span style=\"color: #39af28;\">\u00f6ko\u00a0<\/span>|\u00a0Bild der Wissenschaft, 28. Dezember 2017<br \/>\nForscher haben Einblicke in die Waffentechnik der Pflanzen gewonnen: Wie Z\u00e4hne r\u00fcsten einige Arten die Spitzen ihre feinen H\u00e4rchen mit Kalziumphosphat aus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bestenliste leben\u00a0|\u00a0laufend Hier findet man die besten Produkte f\u00fcr ein nachhaltiges Leben in vielen verschiedenen Sparten. Rausch und Kreativit\u00e4t psychoaktiv\u00a0|\u00a0\u00a0Telepolis, 3. Dezember 2017 Wie welcher Stoff kreativ macht. Schwer zu glauben: dass Shakespeare Kokain rauchte. Holzbauten \u00f6ko\u00a0|\u00a0Spiegel, Online, 3. Dezember 2017 Der urbane Holzbau erlebt eine Renaissance. Das archaische, nachhaltige Material wird von meist jungen<a href=\"https:\/\/www.gaiamedia.org\/deutsch\/2018\/01\/05\/januar-2018-gut-zu-wissen\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/posts\/370"}],"collection":[{"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/comments?post=370"}],"version-history":[{"count":1,"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/posts\/370\/revisions"}],"predecessor-version":[{"id":371,"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/posts\/370\/revisions\/371"}],"wp:attachment":[{"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/media?parent=370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/categories?post=370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaiamedia.org\/deutsch\/wp-json\/wp\/v2\/tags?post=370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}